{"id":39,"date":"2017-04-26T12:33:40","date_gmt":"2017-04-26T12:33:40","guid":{"rendered":"http:\/\/www.alinnova.ch\/?page_id=39"},"modified":"2021-06-11T12:37:22","modified_gmt":"2021-06-11T12:37:22","slug":"checklisten","status":"publish","type":"page","link":"https:\/\/www.alinnova.ch\/index.php\/checklisten\/","title":{"rendered":"Checklisten (Word)"},"content":{"rendered":"<hr \/>\n<p><a href=\"https:\/\/www.alinnova.ch\/wp-content\/uploads\/2021\/06\/Kontrollliste_Economat_wo\u0308chentlich.docx\">Kontrollliste_Economat_monatlich.docx<\/a><\/p>\n<p><a href=\"https:\/\/www.alinnova.ch\/wp-content\/uploads\/2021\/06\/Kontrollliste_Fritteuse.docx\">Kontrollliste_Fritteuse.docx<\/a><\/p>\n<p><a href=\"https:\/\/www.alinnova.ch\/wp-content\/uploads\/2021\/06\/Kontrollliste_Ku\u0308che.doc\">Kontrollliste_K\u00fcche.doc<\/a><\/p>\n<p><a href=\"https:\/\/www.alinnova.ch\/wp-content\/uploads\/2021\/06\/Kontrollliste_Kuehl_TK-Lager.docx\">Kontrollliste_Kuehl_TK-Lager.docx<\/a><\/p>\n<p><a href=\"https:\/\/www.alinnova.ch\/wp-content\/uploads\/2021\/06\/Kontrollliste_Restaurant.docx\">Kontrollliste_Restaurant.docx<\/a><\/p>\n<p><a href=\"https:\/\/www.alinnova.ch\/wp-content\/uploads\/2021\/06\/Kontrollliste_Transporte.docx\">Kontrollliste_Transporte.docx<\/a><\/p>\n<p><a href=\"https:\/\/www.alinnova.ch\/wp-content\/uploads\/2021\/06\/Kontrollliste_Wareneingang.docx\">Kontrollliste_Wareneingang.docx<\/a><\/p>\n<p><a href=\"https:\/\/www.alinnova.ch\/wp-content\/uploads\/2021\/06\/Protokoll_Abweichungen_Schema.docx\">Protokoll_Abweichungen_Schema.docx<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kontrollliste_Economat_monatlich.docx Kontrollliste_Fritteuse.docx Kontrollliste_K\u00fcche.doc Kontrollliste_Kuehl_TK-Lager.docx Kontrollliste_Restaurant.docx Kontrollliste_Transporte.docx Kontrollliste_Wareneingang.docx Protokoll_Abweichungen_Schema.docx<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.alinnova.ch\/index.php\/wp-json\/wp\/v2\/pages\/39"}],"collection":[{"href":"https:\/\/www.alinnova.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.alinnova.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.alinnova.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alinnova.ch\/index.php\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":26,"href":"https:\/\/www.alinnova.ch\/index.php\/wp-json\/wp\/v2\/pages\/39\/revisions"}],"predecessor-version":[{"id":488,"href":"https:\/\/www.alinnova.ch\/index.php\/wp-json\/wp\/v2\/pages\/39\/revisions\/488"}],"wp:attachment":[{"href":"https:\/\/www.alinnova.ch\/index.php\/wp-json\/wp\/v2\/media?parent=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}